{"id":47,"name":"Candide (pseudo)","url":"","description":"<p class=\"x_MsoNormal\">Candide est vieux. Il a des r\u00e9ductions partout. Il a beaucoup voyag\u00e9 dans le monde par envie de voir comment les autres font pour vivre. Il a le bonheur d\u2019avoir de nombreux enfants et petits-enfants. Il a la chance d\u2019avoir un m\u00e9tier qu'il aime. Il ne prendra pas sa retraite. Il aime faire la cuisine et boire du bon vin. Il est d\u00e9j\u00e0 mort une fois, pour de vrai ; ce serait trop long \u00e0 expliquer. La lecture est son voyage ; comment font-ils pour encore nous surprendre ?<\/p>","link":"https:\/\/www.lesmissives.fr\/index.php\/author\/candide\/","slug":"candide","avatar_urls":{"24":"https:\/\/secure.gravatar.com\/avatar\/3bb79357863d60f9d7c17c4f479387c0?s=24&d=mm&r=g","48":"https:\/\/secure.gravatar.com\/avatar\/3bb79357863d60f9d7c17c4f479387c0?s=48&d=mm&r=g","96":"https:\/\/secure.gravatar.com\/avatar\/3bb79357863d60f9d7c17c4f479387c0?s=96&d=mm&r=g"},"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Candide (pseudo), auteur sur Missives<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesmissives.fr\/index.php\/author\/candide\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Candide (pseudo), auteur sur Missives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesmissives.fr\/index.php\/author\/candide\/\" \/>\n<meta property=\"og:site_name\" content=\"Missives\" \/>\n<meta property=\"og:image\" content=\"https:\/\/secure.gravatar.com\/avatar\/3bb79357863d60f9d7c17c4f479387c0?s=500&d=mm&r=g\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/author\/candide\/\",\"url\":\"https:\/\/www.lesmissives.fr\/index.php\/author\/candide\/\",\"name\":\"Candide (pseudo), auteur sur Missives\",\"isPartOf\":{\"@id\":\"http:\/\/www.lesmissives.fr\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/author\/candide\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lesmissives.fr\/index.php\/author\/candide\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/author\/candide\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\/\/www.lesmissives.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archives pour Candide (pseudo)\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.lesmissives.fr\/#website\",\"url\":\"http:\/\/www.lesmissives.fr\/\",\"name\":\"Missives\",\"description\":\"Des livres os\u00e9s et f\u00e9ministes, au sens large\",\"publisher\":{\"@id\":\"http:\/\/www.lesmissives.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.lesmissives.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/www.lesmissives.fr\/#organization\",\"name\":\"les missives\",\"url\":\"http:\/\/www.lesmissives.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\/\/www.lesmissives.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/09\/cropped-LOGO-MISSIVES-ROUGE-COMPLET2-scaled-1.jpg\",\"contentUrl\":\"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/09\/cropped-LOGO-MISSIVES-ROUGE-COMPLET2-scaled-1.jpg\",\"width\":1130,\"height\":800,\"caption\":\"les missives\"},\"image\":{\"@id\":\"http:\/\/www.lesmissives.fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/LesMissives\/\"]},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.lesmissives.fr\/#\/schema\/person\/9540e1463bcbe826950b3e7b8ef4de74\",\"name\":\"Candide (pseudo)\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\/\/www.lesmissives.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3bb79357863d60f9d7c17c4f479387c0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3bb79357863d60f9d7c17c4f479387c0?s=96&d=mm&r=g\",\"caption\":\"Candide (pseudo)\"},\"description\":\"Candide est vieux. Il a des r\u00e9ductions partout. Il a beaucoup voyag\u00e9 dans le monde par envie de voir comment les autres font pour vivre. Il a le bonheur d\u2019avoir de nombreux enfants et petits-enfants. Il a la chance d\u2019avoir un m\u00e9tier qu'il aime. Il ne prendra pas sa retraite. Il aime faire la cuisine et boire du bon vin. Il est d\u00e9j\u00e0 mort une fois, pour de vrai ; ce serait trop long \u00e0 expliquer. La lecture est son voyage ; comment font-ils pour encore nous surprendre ?\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/author\/candide\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Candide (pseudo), auteur sur Missives","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesmissives.fr\/index.php\/author\/candide\/","og_locale":"fr_FR","og_type":"profile","og_title":"Candide (pseudo), auteur sur Missives","og_url":"https:\/\/www.lesmissives.fr\/index.php\/author\/candide\/","og_site_name":"Missives","og_image":[{"url":"https:\/\/secure.gravatar.com\/avatar\/3bb79357863d60f9d7c17c4f479387c0?s=500&d=mm&r=g"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/www.lesmissives.fr\/index.php\/author\/candide\/","url":"https:\/\/www.lesmissives.fr\/index.php\/author\/candide\/","name":"Candide (pseudo), auteur sur Missives","isPartOf":{"@id":"http:\/\/www.lesmissives.fr\/#website"},"breadcrumb":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/author\/candide\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesmissives.fr\/index.php\/author\/candide\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesmissives.fr\/index.php\/author\/candide\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/www.lesmissives.fr\/"},{"@type":"ListItem","position":2,"name":"Archives pour Candide (pseudo)"}]},{"@type":"WebSite","@id":"http:\/\/www.lesmissives.fr\/#website","url":"http:\/\/www.lesmissives.fr\/","name":"Missives","description":"Des livres os\u00e9s et f\u00e9ministes, au sens large","publisher":{"@id":"http:\/\/www.lesmissives.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.lesmissives.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"http:\/\/www.lesmissives.fr\/#organization","name":"les missives","url":"http:\/\/www.lesmissives.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/www.lesmissives.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/09\/cropped-LOGO-MISSIVES-ROUGE-COMPLET2-scaled-1.jpg","contentUrl":"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/09\/cropped-LOGO-MISSIVES-ROUGE-COMPLET2-scaled-1.jpg","width":1130,"height":800,"caption":"les missives"},"image":{"@id":"http:\/\/www.lesmissives.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LesMissives\/"]},{"@type":"Person","@id":"http:\/\/www.lesmissives.fr\/#\/schema\/person\/9540e1463bcbe826950b3e7b8ef4de74","name":"Candide (pseudo)","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/www.lesmissives.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3bb79357863d60f9d7c17c4f479387c0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3bb79357863d60f9d7c17c4f479387c0?s=96&d=mm&r=g","caption":"Candide (pseudo)"},"description":"Candide est vieux. Il a des r\u00e9ductions partout. Il a beaucoup voyag\u00e9 dans le monde par envie de voir comment les autres font pour vivre. Il a le bonheur d\u2019avoir de nombreux enfants et petits-enfants. Il a la chance d\u2019avoir un m\u00e9tier qu'il aime. Il ne prendra pas sa retraite. Il aime faire la cuisine et boire du bon vin. Il est d\u00e9j\u00e0 mort une fois, pour de vrai ; ce serait trop long \u00e0 expliquer. La lecture est son voyage ; comment font-ils pour encore nous surprendre ?","mainEntityOfPage":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/author\/candide\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/users\/47"}],"collection":[{"href":"https:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/users"}]}}