{"id":6809,"date":"2026-01-09T15:23:04","date_gmt":"2026-01-09T14:23:04","guid":{"rendered":"https:\/\/www.lesmissives.fr\/?p=6809"},"modified":"2026-01-09T15:23:05","modified_gmt":"2026-01-09T14:23:05","slug":"sororites-en-revolution-bonnes-revolutions-pour-2026","status":"publish","type":"post","link":"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/","title":{"rendered":"Sororit\u00e9s en r\u00e9volution\u00a0: bonnes r\u00e9volutions pour 2026"},"content":{"rendered":"\n<p>R\u00e9solutions 2026&nbsp;: Lire plus d\u2019autrices, il y en a tellement encore \u00e0 d\u00e9couvrir. Se battre pour nos droits reproductifs. D\u00e9noncer, malgr\u00e9 l\u2019\u00e9puisement, les violences dont nous et nos s\u0153urs sommes victimes. Inventer des collectifs inimagin\u00e9s. Ne pas c\u00e9der d\u2019un pouce sur nos avanc\u00e9es scientifiques, politiques, po\u00e9tiques. \u00catre badass, \u00eatre looseuses, \u00ab&nbsp;pas des h\u00e9ro\u00efnes toujours des guerri\u00e8res&nbsp;\u00bb, celles qui savent savent. Prendre la parole. \u00c9couter les dissonances. Questionner le genre. Cramer le patriarcat. R\u00eaver l\u2019avenir. R\u00e9\u00e9crire l\u2019histoire.<\/p>\n\n\n\n<p>Faire un burnout.<\/p>\n\n\n\n<p>On peut pas \u00eatre sur tous les fronts. C\u2019est vrai dans ta vie, d\u2019ailleurs moi non plus j\u2019ai pas r\u00e9ussi \u00e0 g\u00e9rer l\u2019orthodontiste et les devoirs hier alors j\u2019ai culpabilis\u00e9 et ensuite j\u2019ai reculpabilis\u00e9 d\u2019avoir culpabilis\u00e9 et d\u2019\u00eatre une bad feminist. C\u2019est vrai en litt\u00e9rature aussi. C\u2019est un \u00e9cueil auquel on doit faire gaffe, comme lectrices, comme chroniqueuses et comme autrices\u00a0: y a pas de roman qui coche toutes les cases de toutes les femmes, qui performe un engagement irr\u00e9prochable sur tous les fronts. Y a pas d\u2019autrice qui ait port\u00e9 toute seule tous les combats sans s\u2019effondrer. Y a pas d\u2019\u0153uvre ultime \u00e0 attendre ou \u00e0 \u00e9crire, qui ferait r\u00e9sonner tous nos combats, tous nos traumas, \u00e0 nous toutes.<\/p>\n\n\n\n<p>Heureusement, on n\u2019est pas seules.<\/p>\n\n\n\n<p>Elle est l\u00e0, la seule \u0153uvre qui te parlera \u00e0 la fois d\u2019allaitement et de f\u00e9minicide, de conjugalit\u00e9 face au vieillissement et de violence \u00e9ducative, de confiscation saniste de la parole et de transmission matriarcale&nbsp;; qui te parlera aussi de tout le reste, de th\u00e8mes qui ne sont pas class\u00e9s au rayon \u00ab&nbsp;f\u00e9minisme&nbsp;\u00bb de ta biblioth\u00e8que alors que pourtant, comme la recherche m\u00e9dicale et scientifique, la vie priv\u00e9e, la vie publique&nbsp;; qui te parlera dans ta langue et dans celles que tu n\u2019as pas l\u2019habitude d\u2019entendre, celles du conte et du surr\u00e9alisme, celles de l\u2019horreur et de l\u2019\u00e9pop\u00e9e, toutes celles qu\u2019on n\u2019ose pas toujours pratiquer.<\/p>\n\n\n\n<p>\u00c9videmment que c\u2019est une anthologie.<\/p>\n\n\n\n<p>Ladies and ladies, please welcome <em>Sororit\u00e9s en r\u00e9volution<\/em>, l\u2019anthologie dirig\u00e9e par Ann et Jeff Vandermeer, collectivement traduite en fran\u00e7ais pour les \u00e9ditions Goater.<\/p>\n\n\n\n<p>La fan de SF que je suis \u00e9tait un peu d\u00e9pit\u00e9e que certains textes de l\u2019antho originelle ne puissent y figurer, pour des questions de droits \u2013 ce qui nous prive des nouvelles de mes <em>queens<\/em> Ursula Le Guin, Octavia Butler, James Tiptree Jr ou Joanna Russ, entre autres. Mais malgr\u00e9 leur absence, le recueil est vraiment aussi remarquable pour qui veut s\u2019initier s\u00e9rieusement \u00e0 la SF f\u00e9minine que pour qui veut retrouver des ic\u00f4nes d\u00e9j\u00e0 famili\u00e8res. Il rassemble des textes d\u2019origines vari\u00e9es&nbsp;: malgr\u00e9 une surrepr\u00e9sentation am\u00e9ricaine attendue, on trouve la franco-qu\u00e9b\u00e9coise Elisabeth Vonarburg, l\u2019argentine Angelica Gorodischer ou la su\u00e9doise Karin Tidbeck, par exemple&nbsp;; il couvre aussi une vaste p\u00e9riode, remontant \u00e0 la surr\u00e9aliste Leonora Carrington et \u00e0 des plumes de l\u2019envol des ann\u00e9es 70, comme Tanith Lee, pour s\u2019\u00e9tendre jusqu\u2019au d\u00e9but des ann\u00e9es 2010. Des textes tr\u00e8s brefs c\u00f4toient de longues nouvelles&nbsp;; la litt\u00e9rature exp\u00e9rimentale succ\u00e8de \u00e0 la narration classique. Bref, y en a pour tout le monde.<\/p>\n\n\n\n<p>Et une \u0153uvre pareille nous lib\u00e8re de cette pression existentielle et litt\u00e9raire de vouloir tout faire tout le temps. On se relaie. On s\u2019\u00e9paule, sans m\u00eame s\u2019\u00eatre rencontr\u00e9es, juste parce que quelque part, pour un moment, des paroles s\u2019entrecroisent.<\/p>\n\n\n\n<p>La notion de \u00ab&nbsp;coup de c\u0153ur&nbsp;\u00bb me gonfle, alors je vais lui substituer celle de \u00ab&nbsp;textes qui me travaillent encore deux semaines apr\u00e8s&nbsp;\u00bb. Deux tr\u00e8s belles trads de Marie Koullen, avec \u00ab&nbsp;Les paroles interdites de Marguerite A.&nbsp;\u00bb de L. Timmel Duchamp, la nouvelle qui ouvre le recueil par une interview de celle dont la parole est jug\u00e9e si dangereuse qu\u2019elle doit \u00eatre incarc\u00e9r\u00e9e, et \u00ab&nbsp;Les cinq filles de la grammairienne&nbsp;\u00bb d\u2019Eleanor Arnasson, l\u2019un des plus beaux contes que j\u2019ai lu, o\u00f9 chaque fille doit faire sa route avec le pouvoir d\u2019une classe grammaticale, embellir le monde gr\u00e2ce aux adjectifs ou apaiser les d\u00e9bats par le pouvoir des pr\u00e9positions. Deux variations sur la m\u00e9tamorphose v\u00e9g\u00e9tale, versant r\u00e9alisme magique pour \u00ab&nbsp;Les hommes qui vivent dans les arbres&nbsp;\u00bb de Kelly Barnhill, qui bouscule les fronti\u00e8res du corps et du genre, et versant psychologie surr\u00e9aliste pour \u00ab&nbsp;Un sommeil de plante&nbsp;\u00bb d\u2019Ann Richter, lente transformation hibernante, parfaite pour la saison. La bouleversante \u00ab&nbsp;Gestella&nbsp;\u00bb de Susan Palwick, dont l\u2019h\u00e9ro\u00efne loup-garou, parce qu\u2019elle vieillit au rythme des chiens, est peu \u00e0 peu abandonn\u00e9e par son connard de conjoint. Le vertige de \u00ab&nbsp;Treize mani\u00e8res d\u2019observer l\u2019Espace\/Temps&nbsp;\u00bb de Catherynne M. Valente, tissage de cosmogonies et d\u2019\u00e9criture autobiographique o\u00f9 se r\u00e9pondent l\u2019intime et le cosmique. Mais vraiment, le tout est sup\u00e9rieur \u00e0 la somme de ses parties, et les conflagrations qu\u2019induit le passage d\u2019un texte \u00e0 l\u2019autre \u2013 de la dystopie \u00e0 l\u2019horreur, de la po\u00e9sie au post-apo \u2013 fait la puissance de l\u2019exp\u00e9rience.<\/p>\n\n\n\n<p>R\u00e9volutions 2026&nbsp;: courage.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9solutions 2026&nbsp;: Lire plus d\u2019autrices, il y en a tellement encore \u00e0 d\u00e9couvrir. Se battre pour nos droits reproductifs. D\u00e9noncer, malgr\u00e9 l\u2019\u00e9puisement, les violences dont nous et nos s\u0153urs sommes victimes. Inventer des collectifs inimagin\u00e9s. Ne pas c\u00e9der d\u2019un pouce sur nos avanc\u00e9es scientifiques, politiques, po\u00e9tiques. \u00catre badass, \u00eatre looseuses, \u00ab&nbsp;pas des h\u00e9ro\u00efnes toujours des [&hellip;]<\/p>\n","protected":false},"author":49,"featured_media":6811,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35],"tags":[],"class_list":["post-6809","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fantasy","has-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sororit\u00e9s en r\u00e9volution\u00a0: bonnes r\u00e9volutions pour 2026 - Missives<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sororit\u00e9s en r\u00e9volution\u00a0: bonnes r\u00e9volutions pour 2026 - Missives\" \/>\n<meta property=\"og:description\" content=\"R\u00e9solutions 2026&nbsp;: Lire plus d\u2019autrices, il y en a tellement encore \u00e0 d\u00e9couvrir. Se battre pour nos droits reproductifs. D\u00e9noncer, malgr\u00e9 l\u2019\u00e9puisement, les violences dont nous et nos s\u0153urs sommes victimes. Inventer des collectifs inimagin\u00e9s. Ne pas c\u00e9der d\u2019un pouce sur nos avanc\u00e9es scientifiques, politiques, po\u00e9tiques. \u00catre badass, \u00eatre looseuses, \u00ab&nbsp;pas des h\u00e9ro\u00efnes toujours des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Missives\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LesMissives\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-09T14:23:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-09T14:23:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2026\/01\/goater.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"636\" \/>\n\t<meta property=\"og:image:height\" content=\"506\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M\u00e9lanie Fievet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"M\u00e9lanie Fievet\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/\"},\"author\":{\"name\":\"M\u00e9lanie Fievet\",\"@id\":\"https:\/\/www.lesmissives.fr\/#\/schema\/person\/b2c3b36921629b8873e996cc36afe38f\"},\"headline\":\"Sororit\u00e9s en r\u00e9volution\u00a0: bonnes r\u00e9volutions pour 2026\",\"datePublished\":\"2026-01-09T14:23:04+00:00\",\"dateModified\":\"2026-01-09T14:23:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/\"},\"wordCount\":936,\"publisher\":{\"@id\":\"https:\/\/www.lesmissives.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2026\/01\/1000011116-scaled.jpg\",\"articleSection\":[\"Fantasy\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/\",\"url\":\"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/\",\"name\":\"Sororit\u00e9s en r\u00e9volution\u00a0: bonnes r\u00e9volutions pour 2026 - Missives\",\"isPartOf\":{\"@id\":\"https:\/\/www.lesmissives.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2026\/01\/1000011116-scaled.jpg\",\"datePublished\":\"2026-01-09T14:23:04+00:00\",\"dateModified\":\"2026-01-09T14:23:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/#primaryimage\",\"url\":\"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2026\/01\/1000011116-scaled.jpg\",\"contentUrl\":\"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2026\/01\/1000011116-scaled.jpg\",\"width\":600,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lesmissives.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sororit\u00e9s en r\u00e9volution\u00a0: bonnes r\u00e9volutions pour 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lesmissives.fr\/#website\",\"url\":\"https:\/\/www.lesmissives.fr\/\",\"name\":\"Missives\",\"description\":\"Des livres os\u00e9s et f\u00e9ministes, au sens large\",\"publisher\":{\"@id\":\"https:\/\/www.lesmissives.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lesmissives.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lesmissives.fr\/#organization\",\"name\":\"les missives\",\"url\":\"https:\/\/www.lesmissives.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lesmissives.fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/09\/cropped-LOGO-MISSIVES-ROUGE-COMPLET2-scaled-1.jpg\",\"contentUrl\":\"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/09\/cropped-LOGO-MISSIVES-ROUGE-COMPLET2-scaled-1.jpg\",\"width\":1130,\"height\":800,\"caption\":\"les missives\"},\"image\":{\"@id\":\"https:\/\/www.lesmissives.fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/LesMissives\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lesmissives.fr\/#\/schema\/person\/b2c3b36921629b8873e996cc36afe38f\",\"name\":\"M\u00e9lanie Fievet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lesmissives.fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9cbafea05f021e05f022b4403c74717d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9cbafea05f021e05f022b4403c74717d?s=96&d=mm&r=g\",\"caption\":\"M\u00e9lanie Fievet\"},\"description\":\"M\u00e9lanie se balade depuis pas mal d'ann\u00e9es dans les mondes litt\u00e9raires et ludiques de l'imaginaire, avec un peu de recherche universitaire sur les mythes, les \u00e2mes et les dragons, un peu d'\u00e9criture de nouvelles, et beaucoup de lecture. De temps en temps, elle en sort parce que les programmes de l'\u00c9ducation nationale exigent qu'on parle d'autre chose aux lyc\u00e9en\u00b7nes. Elle est convaincue qu'il y a des milliers de tr\u00e9sors \u00e0 partager en SF et en fantasy, et que le cocktail h\u00e9ros couillu, mentor barbu et r\u00e9cit convenu n'y est pas une fatalit\u00e9.\",\"url\":\"https:\/\/www.lesmissives.fr\/index.php\/author\/melaniefievet\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sororit\u00e9s en r\u00e9volution\u00a0: bonnes r\u00e9volutions pour 2026 - Missives","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/","og_locale":"fr_FR","og_type":"article","og_title":"Sororit\u00e9s en r\u00e9volution\u00a0: bonnes r\u00e9volutions pour 2026 - Missives","og_description":"R\u00e9solutions 2026&nbsp;: Lire plus d\u2019autrices, il y en a tellement encore \u00e0 d\u00e9couvrir. Se battre pour nos droits reproductifs. D\u00e9noncer, malgr\u00e9 l\u2019\u00e9puisement, les violences dont nous et nos s\u0153urs sommes victimes. Inventer des collectifs inimagin\u00e9s. Ne pas c\u00e9der d\u2019un pouce sur nos avanc\u00e9es scientifiques, politiques, po\u00e9tiques. \u00catre badass, \u00eatre looseuses, \u00ab&nbsp;pas des h\u00e9ro\u00efnes toujours des [&hellip;]","og_url":"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/","og_site_name":"Missives","article_publisher":"https:\/\/www.facebook.com\/LesMissives\/","article_published_time":"2026-01-09T14:23:04+00:00","article_modified_time":"2026-01-09T14:23:05+00:00","og_image":[{"width":636,"height":506,"url":"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2026\/01\/goater.jpg","type":"image\/jpeg"}],"author":"M\u00e9lanie Fievet","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"M\u00e9lanie Fievet","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/#article","isPartOf":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/"},"author":{"name":"M\u00e9lanie Fievet","@id":"https:\/\/www.lesmissives.fr\/#\/schema\/person\/b2c3b36921629b8873e996cc36afe38f"},"headline":"Sororit\u00e9s en r\u00e9volution\u00a0: bonnes r\u00e9volutions pour 2026","datePublished":"2026-01-09T14:23:04+00:00","dateModified":"2026-01-09T14:23:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/"},"wordCount":936,"publisher":{"@id":"https:\/\/www.lesmissives.fr\/#organization"},"image":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2026\/01\/1000011116-scaled.jpg","articleSection":["Fantasy"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/","url":"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/","name":"Sororit\u00e9s en r\u00e9volution\u00a0: bonnes r\u00e9volutions pour 2026 - Missives","isPartOf":{"@id":"https:\/\/www.lesmissives.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/#primaryimage"},"image":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2026\/01\/1000011116-scaled.jpg","datePublished":"2026-01-09T14:23:04+00:00","dateModified":"2026-01-09T14:23:05+00:00","breadcrumb":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/#primaryimage","url":"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2026\/01\/1000011116-scaled.jpg","contentUrl":"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2026\/01\/1000011116-scaled.jpg","width":600,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesmissives.fr\/index.php\/2026\/01\/09\/sororites-en-revolution-bonnes-revolutions-pour-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lesmissives.fr\/"},{"@type":"ListItem","position":2,"name":"Sororit\u00e9s en r\u00e9volution\u00a0: bonnes r\u00e9volutions pour 2026"}]},{"@type":"WebSite","@id":"https:\/\/www.lesmissives.fr\/#website","url":"https:\/\/www.lesmissives.fr\/","name":"Missives","description":"Des livres os\u00e9s et f\u00e9ministes, au sens large","publisher":{"@id":"https:\/\/www.lesmissives.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesmissives.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesmissives.fr\/#organization","name":"les missives","url":"https:\/\/www.lesmissives.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesmissives.fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/09\/cropped-LOGO-MISSIVES-ROUGE-COMPLET2-scaled-1.jpg","contentUrl":"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/09\/cropped-LOGO-MISSIVES-ROUGE-COMPLET2-scaled-1.jpg","width":1130,"height":800,"caption":"les missives"},"image":{"@id":"https:\/\/www.lesmissives.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LesMissives\/"]},{"@type":"Person","@id":"https:\/\/www.lesmissives.fr\/#\/schema\/person\/b2c3b36921629b8873e996cc36afe38f","name":"M\u00e9lanie Fievet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesmissives.fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9cbafea05f021e05f022b4403c74717d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9cbafea05f021e05f022b4403c74717d?s=96&d=mm&r=g","caption":"M\u00e9lanie Fievet"},"description":"M\u00e9lanie se balade depuis pas mal d'ann\u00e9es dans les mondes litt\u00e9raires et ludiques de l'imaginaire, avec un peu de recherche universitaire sur les mythes, les \u00e2mes et les dragons, un peu d'\u00e9criture de nouvelles, et beaucoup de lecture. De temps en temps, elle en sort parce que les programmes de l'\u00c9ducation nationale exigent qu'on parle d'autre chose aux lyc\u00e9en\u00b7nes. Elle est convaincue qu'il y a des milliers de tr\u00e9sors \u00e0 partager en SF et en fantasy, et que le cocktail h\u00e9ros couillu, mentor barbu et r\u00e9cit convenu n'y est pas une fatalit\u00e9.","url":"https:\/\/www.lesmissives.fr\/index.php\/author\/melaniefievet\/"}]}},"_links":{"self":[{"href":"https:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/posts\/6809"}],"collection":[{"href":"https:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/comments?post=6809"}],"version-history":[{"count":2,"href":"https:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/posts\/6809\/revisions"}],"predecessor-version":[{"id":6813,"href":"https:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/posts\/6809\/revisions\/6813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/media\/6811"}],"wp:attachment":[{"href":"https:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/media?parent=6809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/categories?post=6809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/tags?post=6809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}