{"id":6447,"date":"2025-05-21T17:33:00","date_gmt":"2025-05-21T15:33:00","guid":{"rendered":"https:\/\/www.lesmissives.fr\/?p=6447"},"modified":"2025-05-21T17:47:26","modified_gmt":"2025-05-21T15:47:26","slug":"missives-en-ecoute-59-safiya-sinclair-dire-babylone","status":"publish","type":"post","link":"http:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/","title":{"rendered":"Missives en \u00e9coute #59 : Safiya Sinclair, Dire Babylone"},"content":{"rendered":"\n<p><em>Dire Babylone<\/em> c&rsquo;est l&rsquo;histoire personne et incroyable de Safiya Sinclair qui se cr\u00e9e un avenir gr\u00e2ce \u00e0 la po\u00e9sie (celle qui la sauve et celle qu&rsquo;elle \u00e9crit) mais c&rsquo;est aussi l&rsquo;histoire plus m\u00e9connue des rastas, sorte de symbole international de la Jama\u00efque et pourtant minorit\u00e9 pers\u00e9cut\u00e9e dans le pays.<\/p>\n\n\n\n<p><em>Dire Babylone<\/em> c&rsquo;est surtout un r\u00e9cit d&rsquo;\u00e9mancipation, celle d&rsquo;une m\u00e8re victime de l&#8217;emprise de son mari, celle d&rsquo;une fille qui fait face \u00e0 la pression terrifiante de son p\u00e8re et finalement celle de la belle relation que ces deux femmes nouent sur le chemin de leur libert\u00e9.<\/p>\n\n\n\n<p>Paru aux \u00e9ditions Buchet Chastel.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video controls src=\"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/05\/ENTREnosLIGNES_ep59.mp4\"><\/video><\/figure>\n\n\n\n<p><em>Entre nos lignes, la capsule sonore et litt\u00e9raire de notre rubrique Missives en \u00e9coute se transforme en podcast, disponible sur la plupart des plateformes d\u2019\u00e9coute et <a href=\"https:\/\/shows.acast.com\/entre-nos-lignes\">sur Acast<\/a><\/em>.<\/p>\n\n\n\n<p><em>Entre nos lignes, c\u2019est une dose de pens\u00e9es inspirantes et engag\u00e9es, propos\u00e9es selon l\u2019humeur ou l\u2019actualit\u00e9, quelques lignes d\u2019un auteur ou d\u2019une autrice lues par la com\u00e9dienne&nbsp;<a rel=\"noreferrer noopener\" href=\"https:\/\/www.instagram.com\/marieemiliem\/?hl=fr\" target=\"_blank\">Marie-\u00c9milie Michel<\/a>.<\/em><\/p>\n\n\n\n<p><em>Une lecture sans commentaire o\u00f9 seuls comptent les mots.<\/em><\/p>\n\n\n\n<p><em>Entre nos lignes donne \u00e0 entendre des extraits de romans mais aussi de la po\u00e9sie, des essais, de la nouveaut\u00e9 comme du classique mais des livres toujours os\u00e9s et f\u00e9ministes, au sens large !<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dire Babylone c&rsquo;est l&rsquo;histoire personne et incroyable de Safiya Sinclair qui se cr\u00e9e un avenir gr\u00e2ce \u00e0 la po\u00e9sie (celle qui la sauve et celle qu&rsquo;elle \u00e9crit) mais c&rsquo;est aussi l&rsquo;histoire plus m\u00e9connue des rastas, sorte de symbole international de la Jama\u00efque et pourtant minorit\u00e9 pers\u00e9cut\u00e9e dans le pays. Dire Babylone c&rsquo;est surtout un r\u00e9cit [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":6449,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-6447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-missives-en-ecoute","has-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Missives en \u00e9coute #59 : Safiya Sinclair, Dire Babylone - Missives<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Missives en \u00e9coute #59 : Safiya Sinclair, Dire Babylone - Missives\" \/>\n<meta property=\"og:description\" content=\"Dire Babylone c&rsquo;est l&rsquo;histoire personne et incroyable de Safiya Sinclair qui se cr\u00e9e un avenir gr\u00e2ce \u00e0 la po\u00e9sie (celle qui la sauve et celle qu&rsquo;elle \u00e9crit) mais c&rsquo;est aussi l&rsquo;histoire plus m\u00e9connue des rastas, sorte de symbole international de la Jama\u00efque et pourtant minorit\u00e9 pers\u00e9cut\u00e9e dans le pays. Dire Babylone c&rsquo;est surtout un r\u00e9cit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/\" \/>\n<meta property=\"og:site_name\" content=\"Missives\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LesMissives\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-21T15:33:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-21T15:47:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/05\/babylone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"813\" \/>\n\t<meta property=\"og:image:height\" content=\"427\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marie-\u00c9milie Michel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marie-\u00c9milie Michel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/\"},\"author\":{\"name\":\"Marie-\u00c9milie Michel\",\"@id\":\"https:\/\/www.lesmissives.fr\/#\/schema\/person\/fe0f1735e47e39cddf6bebea8159eec6\"},\"headline\":\"Missives en \u00e9coute #59 : Safiya Sinclair, Dire Babylone\",\"datePublished\":\"2025-05-21T15:33:00+00:00\",\"dateModified\":\"2025-05-21T15:47:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/\"},\"wordCount\":231,\"publisher\":{\"@id\":\"https:\/\/www.lesmissives.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/05\/19_9782283038253_1_75.jpg\",\"articleSection\":[\"Missives en \u00e9coute\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/\",\"url\":\"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/\",\"name\":\"Missives en \u00e9coute #59 : Safiya Sinclair, Dire Babylone - Missives\",\"isPartOf\":{\"@id\":\"https:\/\/www.lesmissives.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/05\/19_9782283038253_1_75.jpg\",\"datePublished\":\"2025-05-21T15:33:00+00:00\",\"dateModified\":\"2025-05-21T15:47:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/#primaryimage\",\"url\":\"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/05\/19_9782283038253_1_75.jpg\",\"contentUrl\":\"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/05\/19_9782283038253_1_75.jpg\",\"width\":546,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lesmissives.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Missives en \u00e9coute #59 : Safiya Sinclair, Dire Babylone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lesmissives.fr\/#website\",\"url\":\"https:\/\/www.lesmissives.fr\/\",\"name\":\"Missives\",\"description\":\"Des livres os\u00e9s et f\u00e9ministes, au sens large\",\"publisher\":{\"@id\":\"https:\/\/www.lesmissives.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lesmissives.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lesmissives.fr\/#organization\",\"name\":\"les missives\",\"url\":\"https:\/\/www.lesmissives.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lesmissives.fr\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/09\/cropped-LOGO-MISSIVES-ROUGE-COMPLET2-scaled-1.jpg\",\"contentUrl\":\"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/09\/cropped-LOGO-MISSIVES-ROUGE-COMPLET2-scaled-1.jpg\",\"width\":1130,\"height\":800,\"caption\":\"les missives\"},\"image\":{\"@id\":\"https:\/\/www.lesmissives.fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/LesMissives\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lesmissives.fr\/#\/schema\/person\/fe0f1735e47e39cddf6bebea8159eec6\",\"name\":\"Marie-\u00c9milie Michel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lesmissives.fr\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/f7fb41420d27b64c57fb71b769004666?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/f7fb41420d27b64c57fb71b769004666?s=96&d=mm&r=g\",\"caption\":\"Marie-\u00c9milie Michel\"},\"description\":\"Com\u00e9dienne, co-directrice artistique du collectif Lilalune etc, Marie-Emilie s'int\u00e9resse particuli\u00e8rement \u00e0 la question des femmes dans son travail sc\u00e9nique. Peut-\u00eatre parce qu'elle a \u00e9tudi\u00e9 le journalisme et qu'elle voit tout texte comme une mati\u00e8re vivante, elle a \u00e9galement initi\u00e9 des \\\"lectures citoyennes\\\" : reflets de questionnements li\u00e9s \u00e0 un th\u00e8me d'actualit\u00e9, assemblage de regards et de textes, men\u00e9es \u00e0 trois voix. La derni\u00e8re en date s'appelait \\\"F\u00e9ministe, ta m\u00e8re\\\"!\u00a0C'est donc tout naturellement que sa passion des mots et son engagement f\u00e9ministe l'ont men\u00e9e \u00e0 partager ses lectures sur Missives.\",\"url\":\"http:\/\/www.lesmissives.fr\/index.php\/author\/marieemiliemichel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Missives en \u00e9coute #59 : Safiya Sinclair, Dire Babylone - Missives","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/","og_locale":"fr_FR","og_type":"article","og_title":"Missives en \u00e9coute #59 : Safiya Sinclair, Dire Babylone - Missives","og_description":"Dire Babylone c&rsquo;est l&rsquo;histoire personne et incroyable de Safiya Sinclair qui se cr\u00e9e un avenir gr\u00e2ce \u00e0 la po\u00e9sie (celle qui la sauve et celle qu&rsquo;elle \u00e9crit) mais c&rsquo;est aussi l&rsquo;histoire plus m\u00e9connue des rastas, sorte de symbole international de la Jama\u00efque et pourtant minorit\u00e9 pers\u00e9cut\u00e9e dans le pays. Dire Babylone c&rsquo;est surtout un r\u00e9cit [&hellip;]","og_url":"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/","og_site_name":"Missives","article_publisher":"https:\/\/www.facebook.com\/LesMissives\/","article_published_time":"2025-05-21T15:33:00+00:00","article_modified_time":"2025-05-21T15:47:26+00:00","og_image":[{"width":813,"height":427,"url":"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/05\/babylone.jpg","type":"image\/jpeg"}],"author":"Marie-\u00c9milie Michel","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Marie-\u00c9milie Michel","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/#article","isPartOf":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/"},"author":{"name":"Marie-\u00c9milie Michel","@id":"https:\/\/www.lesmissives.fr\/#\/schema\/person\/fe0f1735e47e39cddf6bebea8159eec6"},"headline":"Missives en \u00e9coute #59 : Safiya Sinclair, Dire Babylone","datePublished":"2025-05-21T15:33:00+00:00","dateModified":"2025-05-21T15:47:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/"},"wordCount":231,"publisher":{"@id":"https:\/\/www.lesmissives.fr\/#organization"},"image":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/#primaryimage"},"thumbnailUrl":"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/05\/19_9782283038253_1_75.jpg","articleSection":["Missives en \u00e9coute"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/","url":"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/","name":"Missives en \u00e9coute #59 : Safiya Sinclair, Dire Babylone - Missives","isPartOf":{"@id":"https:\/\/www.lesmissives.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/#primaryimage"},"image":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/#primaryimage"},"thumbnailUrl":"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/05\/19_9782283038253_1_75.jpg","datePublished":"2025-05-21T15:33:00+00:00","dateModified":"2025-05-21T15:47:26+00:00","breadcrumb":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/#primaryimage","url":"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/05\/19_9782283038253_1_75.jpg","contentUrl":"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/05\/19_9782283038253_1_75.jpg","width":546,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesmissives.fr\/index.php\/2025\/05\/21\/missives-en-ecoute-59-safiya-sinclair-dire-babylone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lesmissives.fr\/"},{"@type":"ListItem","position":2,"name":"Missives en \u00e9coute #59 : Safiya Sinclair, Dire Babylone"}]},{"@type":"WebSite","@id":"https:\/\/www.lesmissives.fr\/#website","url":"https:\/\/www.lesmissives.fr\/","name":"Missives","description":"Des livres os\u00e9s et f\u00e9ministes, au sens large","publisher":{"@id":"https:\/\/www.lesmissives.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lesmissives.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lesmissives.fr\/#organization","name":"les missives","url":"https:\/\/www.lesmissives.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesmissives.fr\/#\/schema\/logo\/image\/","url":"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/09\/cropped-LOGO-MISSIVES-ROUGE-COMPLET2-scaled-1.jpg","contentUrl":"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/09\/cropped-LOGO-MISSIVES-ROUGE-COMPLET2-scaled-1.jpg","width":1130,"height":800,"caption":"les missives"},"image":{"@id":"https:\/\/www.lesmissives.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LesMissives\/"]},{"@type":"Person","@id":"https:\/\/www.lesmissives.fr\/#\/schema\/person\/fe0f1735e47e39cddf6bebea8159eec6","name":"Marie-\u00c9milie Michel","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesmissives.fr\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/f7fb41420d27b64c57fb71b769004666?s=96&d=mm&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/f7fb41420d27b64c57fb71b769004666?s=96&d=mm&r=g","caption":"Marie-\u00c9milie Michel"},"description":"Com\u00e9dienne, co-directrice artistique du collectif Lilalune etc, Marie-Emilie s'int\u00e9resse particuli\u00e8rement \u00e0 la question des femmes dans son travail sc\u00e9nique. Peut-\u00eatre parce qu'elle a \u00e9tudi\u00e9 le journalisme et qu'elle voit tout texte comme une mati\u00e8re vivante, elle a \u00e9galement initi\u00e9 des \"lectures citoyennes\" : reflets de questionnements li\u00e9s \u00e0 un th\u00e8me d'actualit\u00e9, assemblage de regards et de textes, men\u00e9es \u00e0 trois voix. La derni\u00e8re en date s'appelait \"F\u00e9ministe, ta m\u00e8re\"!\u00a0C'est donc tout naturellement que sa passion des mots et son engagement f\u00e9ministe l'ont men\u00e9e \u00e0 partager ses lectures sur Missives.","url":"http:\/\/www.lesmissives.fr\/index.php\/author\/marieemiliemichel\/"}]}},"_links":{"self":[{"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/posts\/6447"}],"collection":[{"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/comments?post=6447"}],"version-history":[{"count":4,"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/posts\/6447\/revisions"}],"predecessor-version":[{"id":6457,"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/posts\/6447\/revisions\/6457"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/media\/6449"}],"wp:attachment":[{"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/media?parent=6447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/categories?post=6447"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/tags?post=6447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}