{"id":5212,"date":"2023-08-02T16:38:45","date_gmt":"2023-08-02T14:38:45","guid":{"rendered":"http:\/\/www.lesmissives.fr\/?p=5212"},"modified":"2023-08-02T16:38:45","modified_gmt":"2023-08-02T14:38:45","slug":"avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes","status":"publish","type":"post","link":"http:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/","title":{"rendered":"Avis de grand frais sur le dernier roman de Jean Hegland : Apaiser nos temp\u00eates"},"content":{"rendered":"\n<p>En 2017, 21 ans apr\u00e8s sa parution outre Atlantique, Gallmeister publiait en version fran\u00e7aise l\u2019inoubliable <em><a href=\"http:\/\/www.lesmissives.fr\/index.php\/2020\/10\/29\/dans-la-foret-de-jean-hegland\/\">Dans la for\u00eat<\/a><\/em>&nbsp;qui mettait en sc\u00e8ne deux s\u0153urs \u00e9prouv\u00e9es par une fin du monde imminente face \u00e0 l\u2019effrayante immensit\u00e9 de la nature. En 2021, ce sont les \u00e9ditions Ph\u00e9bus qui nous offrent la publication du deuxi\u00e8me roman de l\u2019autrice, en version fran\u00e7aise, <em>Apaiser nos Temp\u00eates<\/em>, publi\u00e9 en 2004 aux \u00c9tats-Unis. La plume rare, d\u00e9licate et po\u00e9tique de Jean Hegland combin\u00e9e aux destins crois\u00e9s, malmen\u00e9s, fatalement r\u00e9alistes d\u2019Anna et de Cerise dans les affres de la maternit\u00e9 donnent un roman riche en enseignements, r\u00e9flexion et \u00e9motions.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"782\" height=\"468\" src=\"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2023\/07\/BANDEAU-HEGLAND.jpg\" alt=\"\" class=\"wp-image-5214\" srcset=\"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2023\/07\/BANDEAU-HEGLAND.jpg 782w, http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2023\/07\/BANDEAU-HEGLAND-300x180.jpg 300w, http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2023\/07\/BANDEAU-HEGLAND-768x460.jpg 768w, http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2023\/07\/BANDEAU-HEGLAND-400x239.jpg 400w\" sizes=\"(max-width: 782px) 100vw, 782px\" \/><figcaption>Photo : Susan M. Gaines<\/figcaption><\/figure><\/div>\n\n\n\n<p>Entre la publication am\u00e9ricaine en 2004 et celle fran\u00e7aise en 2021, le r\u00e9cit n\u2019en reste pas moins tr\u00e8s contemporain. M\u00eame si l\u2019histoire se passe au d\u00e9but des ann\u00e9es 2000 aux \u00c9tats-Unis, ce qu\u2019\u00e9voque l\u2019autrice dans sa pr\u00e9face demeure d\u2019actualit\u00e9&nbsp;: \u00ab&nbsp;c\u2019est encore sur les m\u00e8res que la charge des enfants p\u00e8se le plus lourd \u2013 les solutions de garde demeurent pr\u00e9caires [\u2026] le droit d\u2019une femme \u00e0 choisir si elle souhaite \u00eatre m\u00e8re est toujours remis en question&nbsp;\u00bb. Elle va m\u00eame plus loin en guise d\u2019avertissement et de ton donn\u00e9s au roman&nbsp;: <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab&nbsp;Il existe peu d\u2019exp\u00e9riences physiques plus intenses, plus intimes et r\u00e9v\u00e9latrices que sont l\u2019acte sexuel, la mort et l\u2019accouchement. Et si la fiction offre un nombre incalculable de sc\u00e8nes de sexe ou de tr\u00e9pas, je n\u2019en ai pas trouv\u00e9 beaucoup qui rendent compte de la souffrance, de la passion et des d\u00e9fis bouleversants d\u2019une naissance.&nbsp;\u00bb <\/p><\/blockquote>\n\n\n\n<p>Lecteur.trice, te voil\u00e0 pr\u00e9venu.e&nbsp;!<\/p>\n\n\n\n<p>Dans ce roman initiatique, on suit le cheminement de deux am\u00e9ricaines issues de milieux distincts qui vont faire face \u00e0 la maternit\u00e9 dans des circonstances radicalement diff\u00e9rentes. Anna, la photographe Wasp de Washington, apr\u00e8s un avortement choisi, donnera naissance \u00e0 Lucy puis Ellen, deux filles plut\u00f4t d\u00e9sir\u00e9es, joliment couv\u00e9es et aim\u00e9es dans les circonstances d\u2019une famille classique et d\u2019un couple h\u00e9t\u00e9ro avec ses hauts et ses bas. Cerise, la californienne, accouchera seule, mal engross\u00e9e, encore ado, rejet\u00e9e par ses parents middle class, de M\u00e9lody puis de Travis, avant de partir sur les routes dans une sorte de fuite en avant de sa vie devenue insipide.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab Mais mourir paraissait terriblement facile, limpide et \u00e9vident, compar\u00e9 \u00e0 ce qu\u2019on exigeait chaque jour d\u2019une femme ordinaire&nbsp;\u00bb<\/p><\/blockquote>\n\n\n\n<p>\u00c0 travers ces deux existences ordinaires que l\u2019on suit sur une douzaine d\u2019ann\u00e9es , Jean Hegland dresse le portrait de deux femmes pers\u00e9v\u00e9rantes, inlassablement battantes, dans leur quotidien occidental, relayant parfois des v\u00e9rit\u00e9s qui d\u00e9rangent&nbsp;: le d\u00e9samour, la fatigue, les choix in\u00e9vitables, l\u2019ali\u00e9nation de la raison. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab&nbsp;J\u2019esp\u00e9rais pouvoir parler de mes personnages sans le sentimentalisme ni le cynisme qui me semblaient caract\u00e9riser la majorit\u00e9 des r\u00e9cits de maternit\u00e9 dans notre culture. (\u2026) Je n\u2019ai pas compris la radicalit\u00e9 de cette ambition avant qu\u2019une premi\u00e8re maison d\u2019\u00e9dition n\u2019annule mon contrat, au motif qu\u2019en g\u00e9n\u00e9ral \u00ab&nbsp;les m\u00e8res n\u2019\u00e9prouvent pas autant d\u2019ambivalence qu\u2019Anna et Cerise vis-\u00e0-vis de leurs enfants&nbsp;\u00bb. <\/p><\/blockquote>\n\n\n\n<p>Jean Hegland met le doigt sur le dicible et ce qu\u2019il faut cacher, pour mieux l\u2019exhiber, entre pudeur, insolence et po\u00e9sie.<\/p>\n\n\n\n<p>En choisissant de rendre visible la vie d\u2019une frange privil\u00e9gi\u00e9e de l\u2019humanit\u00e9 faite m\u00e8re, Jean Hegland se place en porte-parole compatissante, impliqu\u00e9e et jamais moralisatrice. Si on peut s\u2019\u00e9tonner du fait que peu d\u2019hommes n\u2019apparaissent dans <em>Apaiser nos Temp\u00eates<\/em>, il n\u2019y a aucun manich\u00e9isme pour autant, juste une r\u00e9alit\u00e9 criante de ce que signifie, encore une fois, de nos jours, \u00eatre parent\u2026 et \u00eatre m\u00e8re. \u00ab&nbsp;Pour autant tout n\u2019est pas sombre, l\u2019amour, le courage et la d\u00e9votion des parents ne faiblissent pas&nbsp;\u00bb<em>. <\/em>Et heureusement&nbsp;! Mais elle rappelle aussi la solitude, la frustration, le d\u00e9nuement, la sensation de vide.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab&nbsp;On est toutes tellement seules, dans notre r\u00f4le de m\u00e8re. On peut parler \u00e9cole, \u00e9changer les petites choses craquantes qu\u2019ils disent. On peut se plaindre qu\u2019ils nous en font voir. Mais on ne peut pas parler de l\u2019amour terrifiant qu\u2019on leur porte, ni avouer qu\u2019on s\u2019effraie nous-m\u00eames, en essayant de s\u2019occuper d\u2019eux sans perdre la boule.&nbsp;\u00bb<\/p><\/blockquote>\n\n\n\n<h4 class=\"wp-block-heading\">Emprisonner la lumi\u00e8re et capter l\u2019impalpable<\/h4>\n\n\n\n<p>Au-del\u00e0 de cette th\u00e9matique un poil lourde, il est ind\u00e9niable que la lumi\u00e8re est omnipr\u00e9sente dans le roman, et en filigrane son corollaire la noirceur et ce que les ombres r\u00e9v\u00e8lent. Le livre s\u2019ouvre sur la description d\u2019une photographie d\u00e9taill\u00e9e, faisant la part belle aux \u00e9clairages. Plus tard, la grand-m\u00e8re d\u2019Anna, dans une sc\u00e8ne charni\u00e8re sonoris\u00e9e par les tintements des couvercles de confiture se d\u00e9formant sous l\u2019effet de la chaleur, \u00e9voque de mani\u00e8re tr\u00e8s prude et po\u00e9tique sa vision de la chose&nbsp;: <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab&nbsp;Il m\u2019est venu un jour \u00e0 l\u2019esprit que tout ce que je faisais , avec ces conserves, c\u2019\u00e9tait de pr\u00e9server la lumi\u00e8re \u2013 la lumi\u00e8re du soleil (\u2026), celle dont les fruits et les l\u00e9gumes regorgent -, c\u2019\u00e9tait la lumi\u00e8re que je mettais en bocal, et je la pr\u00e9servais dans la cave pour le moment o\u00f9 on en aurait besoin, au milieu de l\u2019hiver&nbsp;\u00bb<\/p><\/blockquote>\n\n\n\n<p>Anna est photographe et son regard sur les gens, son environnement, la mati\u00e8re, est empreint de ce talent. Elle va d\u2019ailleurs nommer son ain\u00e9e Lucy, pr\u00e9nom \u00e0 haute charge familiale mais symbole aussi de l\u2019\u00e9clairante mission qui lui est confi\u00e9e. La reconqu\u00eate du m\u00e9tier d\u2019Anna, qu\u2019elle aura d\u00e9laiss\u00e9 au fil de ses grossesses, jalonne tout le livre. Finalement, lorsque surgissent des arbres couverts de mille fleurs splendides, t\u00e9moins de la vie fertilisant du bois mort, dans un verger abandonn\u00e9, Anna retrouve les sens et son app\u00e9tit mordant perdu. \u00ab&nbsp;H\u00e9b\u00e9t\u00e9e de joie (\u2026) elle \u00e9prouva une gratitude intense et sauvage pour ce qu\u2019\u00e9tait sa vie&nbsp;\u00bb<em>.<\/em> L\u2019aboutissement est criant tant on semble assister Anna dans la renaissance de son art et au-del\u00e0, dans le retour de la f\u00e9minit\u00e9 jaillissante apr\u00e8s la maternit\u00e9 subordonnante. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00ab&nbsp;Vint le moment o\u00f9 la lumi\u00e8re sembla d\u2019une densit\u00e9 parfaite, les ombres aussi riches qu\u2019elles pouvaient possiblement l\u2019\u00eatre. Appuyant sur le d\u00e9clencheur, elle entendit le petit clic de l\u2019obturateur en train de s\u2019ouvrir, sentit son amour pour le monde d\u00e9border de nouveau, et se demanda, \u00e9merveill\u00e9e&nbsp;: Mais o\u00f9 \u00e9tais je pass\u00e9e&nbsp;?&nbsp;\u00bb<\/p><\/blockquote>\n\n\n\n<p>Le roman prend un tournant lorsque Cerise, \u00e9branl\u00e9e par une catastrophe survenant au cours d\u2019un incendie chemine, \u00e0 peine lest\u00e9e de ses possessions rachitiques, avec d\u00e9termination sans regarder en arri\u00e8re. Elle s\u2019\u00e9puise dans une marche cathartique qui ne fait sens que pour elle, pour oublier ce qui ne peut pas l\u2019\u00eatre et forcer la r\u00e9silience. De centre d\u2019h\u00e9bergement d\u2019urgence en programme d\u2019aide aux femmes sans abri, de rencontres en coups de pouce, surviendra dans une sc\u00e8ne d\u2019une beaut\u00e9 \u00e0 couper le souffle \u2013 une ronde d\u2019enfants se peignant les cheveux \u2013  la renaissance de l\u2019espoir, la lueur, l\u2019\u00e9tincelle.<\/p>\n\n\n\n<p> \u00c0 travers l\u2019endurance, la pers\u00e9v\u00e9rance, et le courage forcen\u00e9, Jean Hegland d\u00e9peint ce qu\u2019\u00eatre m\u00e8re et \u00eatre femme peuvent signifier dans un monde individualiste o\u00f9 la sororit\u00e9 \u00e9merge en valeur phare et essentielle.<\/p>\n\n\n\n<p>Elle signe avec <em>Apaiser nos Temp\u00eates <\/em>un indispensable roman bouleversant sur la maternit\u00e9 et ses implications, sur ce qu\u2019\u00eatre m\u00e8re prend comme valeur dans l\u2019adversit\u00e9. Rendons gr\u00e2ce au passage pour le formidable talent de la traductrice Nathalie Bru.<\/p>\n\n\n\n<p>Et si , pour Jean Hegland, \u00ab&nbsp;Les combats et les triomphes de ces femmes continuent \u00e0 \u00e9clairer les miens&nbsp;\u00bb , gageons que cette lecture restera longtemps ancr\u00e9e dans le c\u0153ur de chacun.e de ses lecteur.trices.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 2017, 21 ans apr\u00e8s sa parution outre Atlantique, Gallmeister publiait en version fran\u00e7aise l\u2019inoubliable Dans la for\u00eat&nbsp;qui mettait en sc\u00e8ne deux s\u0153urs \u00e9prouv\u00e9es par une fin du monde imminente face \u00e0 l\u2019effrayante immensit\u00e9 de la nature. En 2021, ce sont les \u00e9ditions Ph\u00e9bus qui nous offrent la publication du deuxi\u00e8me roman de l\u2019autrice, en [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":5213,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-5212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-girl-power-fiction","has-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Avis de grand frais sur le dernier roman de Jean Hegland : Apaiser nos temp\u00eates - Missives<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avis de grand frais sur le dernier roman de Jean Hegland : Apaiser nos temp\u00eates - Missives\" \/>\n<meta property=\"og:description\" content=\"En 2017, 21 ans apr\u00e8s sa parution outre Atlantique, Gallmeister publiait en version fran\u00e7aise l\u2019inoubliable Dans la for\u00eat&nbsp;qui mettait en sc\u00e8ne deux s\u0153urs \u00e9prouv\u00e9es par une fin du monde imminente face \u00e0 l\u2019effrayante immensit\u00e9 de la nature. En 2021, ce sont les \u00e9ditions Ph\u00e9bus qui nous offrent la publication du deuxi\u00e8me roman de l\u2019autrice, en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/\" \/>\n<meta property=\"og:site_name\" content=\"Missives\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LesMissives\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-02T14:38:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2023\/07\/BANDEAU-HEGLAND.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"782\" \/>\n\t<meta property=\"og:image:height\" content=\"468\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e9mence Bauer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e9mence Bauer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/\"},\"author\":{\"name\":\"Cl\u00e9mence Bauer\",\"@id\":\"http:\/\/www.lesmissives.fr\/#\/schema\/person\/be2f3aafb05798c1d3eae466b12b9a48\"},\"headline\":\"Avis de grand frais sur le dernier roman de Jean Hegland : Apaiser nos temp\u00eates\",\"datePublished\":\"2023-08-02T14:38:45+00:00\",\"dateModified\":\"2023-08-02T14:38:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/\"},\"wordCount\":1440,\"publisher\":{\"@id\":\"http:\/\/www.lesmissives.fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2023\/07\/51fL55y67L._AC_UF10001000_QL80_.jpg\",\"articleSection\":[\"Fiction\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/\",\"url\":\"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/\",\"name\":\"Avis de grand frais sur le dernier roman de Jean Hegland : Apaiser nos temp\u00eates - Missives\",\"isPartOf\":{\"@id\":\"http:\/\/www.lesmissives.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2023\/07\/51fL55y67L._AC_UF10001000_QL80_.jpg\",\"datePublished\":\"2023-08-02T14:38:45+00:00\",\"dateModified\":\"2023-08-02T14:38:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/#primaryimage\",\"url\":\"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2023\/07\/51fL55y67L._AC_UF10001000_QL80_.jpg\",\"contentUrl\":\"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2023\/07\/51fL55y67L._AC_UF10001000_QL80_.jpg\",\"width\":539,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"http:\/\/www.lesmissives.fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avis de grand frais sur le dernier roman de Jean Hegland : Apaiser nos temp\u00eates\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.lesmissives.fr\/#website\",\"url\":\"http:\/\/www.lesmissives.fr\/\",\"name\":\"Missives\",\"description\":\"Des livres os\u00e9s et f\u00e9ministes, au sens large\",\"publisher\":{\"@id\":\"http:\/\/www.lesmissives.fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.lesmissives.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"http:\/\/www.lesmissives.fr\/#organization\",\"name\":\"les missives\",\"url\":\"http:\/\/www.lesmissives.fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\/\/www.lesmissives.fr\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/09\/cropped-LOGO-MISSIVES-ROUGE-COMPLET2-scaled-1.jpg\",\"contentUrl\":\"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/09\/cropped-LOGO-MISSIVES-ROUGE-COMPLET2-scaled-1.jpg\",\"width\":1130,\"height\":800,\"caption\":\"les missives\"},\"image\":{\"@id\":\"http:\/\/www.lesmissives.fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/LesMissives\/\"]},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.lesmissives.fr\/#\/schema\/person\/be2f3aafb05798c1d3eae466b12b9a48\",\"name\":\"Cl\u00e9mence Bauer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\/\/www.lesmissives.fr\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/1.gravatar.com\/avatar\/7383069acf91606bc26ab561adaa295a?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/1.gravatar.com\/avatar\/7383069acf91606bc26ab561adaa295a?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e9mence Bauer\"},\"description\":\"Entour\u00e9e de s\u0153urs, tantes, ni\u00e8ces, au c\u0153ur d'un gyn\u00e9c\u00e9e familial, observant la nature depuis toujours et \u0153uvrant dans le domaine agricole depuis 15 ans, Cl\u00e9mence a eu maintes fois l'occasion de se dire que la figure f\u00e9minine, animale ou humaine \u00e9tait plus souvent exploit\u00e9e que dirigeante. Malgr\u00e9 tout, en noyant son bonheur dans le th\u00e9 et le vin de noix, elle s'accroche au fait qu'\u00e0 chaque instant, dans chaque situation, l'\u00e9veil des consciences reste possible, et exp\u00e9rimente chaque jour qu'il n'y a de plus belle valeur que la sororit\u00e9.\",\"url\":\"http:\/\/www.lesmissives.fr\/index.php\/author\/clemencebauer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avis de grand frais sur le dernier roman de Jean Hegland : Apaiser nos temp\u00eates - Missives","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/","og_locale":"fr_FR","og_type":"article","og_title":"Avis de grand frais sur le dernier roman de Jean Hegland : Apaiser nos temp\u00eates - Missives","og_description":"En 2017, 21 ans apr\u00e8s sa parution outre Atlantique, Gallmeister publiait en version fran\u00e7aise l\u2019inoubliable Dans la for\u00eat&nbsp;qui mettait en sc\u00e8ne deux s\u0153urs \u00e9prouv\u00e9es par une fin du monde imminente face \u00e0 l\u2019effrayante immensit\u00e9 de la nature. En 2021, ce sont les \u00e9ditions Ph\u00e9bus qui nous offrent la publication du deuxi\u00e8me roman de l\u2019autrice, en [&hellip;]","og_url":"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/","og_site_name":"Missives","article_publisher":"https:\/\/www.facebook.com\/LesMissives\/","article_published_time":"2023-08-02T14:38:45+00:00","og_image":[{"width":782,"height":468,"url":"https:\/\/www.lesmissives.fr\/wp-content\/uploads\/2023\/07\/BANDEAU-HEGLAND.jpg","type":"image\/jpeg"}],"author":"Cl\u00e9mence Bauer","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Cl\u00e9mence Bauer","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/#article","isPartOf":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/"},"author":{"name":"Cl\u00e9mence Bauer","@id":"http:\/\/www.lesmissives.fr\/#\/schema\/person\/be2f3aafb05798c1d3eae466b12b9a48"},"headline":"Avis de grand frais sur le dernier roman de Jean Hegland : Apaiser nos temp\u00eates","datePublished":"2023-08-02T14:38:45+00:00","dateModified":"2023-08-02T14:38:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/"},"wordCount":1440,"publisher":{"@id":"http:\/\/www.lesmissives.fr\/#organization"},"image":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/#primaryimage"},"thumbnailUrl":"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2023\/07\/51fL55y67L._AC_UF10001000_QL80_.jpg","articleSection":["Fiction"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/","url":"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/","name":"Avis de grand frais sur le dernier roman de Jean Hegland : Apaiser nos temp\u00eates - Missives","isPartOf":{"@id":"http:\/\/www.lesmissives.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/#primaryimage"},"image":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/#primaryimage"},"thumbnailUrl":"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2023\/07\/51fL55y67L._AC_UF10001000_QL80_.jpg","datePublished":"2023-08-02T14:38:45+00:00","dateModified":"2023-08-02T14:38:45+00:00","breadcrumb":{"@id":"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/#primaryimage","url":"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2023\/07\/51fL55y67L._AC_UF10001000_QL80_.jpg","contentUrl":"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2023\/07\/51fL55y67L._AC_UF10001000_QL80_.jpg","width":539,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.lesmissives.fr\/index.php\/2023\/08\/02\/avis-de-grand-frais-sur-le-dernier-roman-de-jean-hegland-apaiser-nos-tempetes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"http:\/\/www.lesmissives.fr\/"},{"@type":"ListItem","position":2,"name":"Avis de grand frais sur le dernier roman de Jean Hegland : Apaiser nos temp\u00eates"}]},{"@type":"WebSite","@id":"http:\/\/www.lesmissives.fr\/#website","url":"http:\/\/www.lesmissives.fr\/","name":"Missives","description":"Des livres os\u00e9s et f\u00e9ministes, au sens large","publisher":{"@id":"http:\/\/www.lesmissives.fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.lesmissives.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"http:\/\/www.lesmissives.fr\/#organization","name":"les missives","url":"http:\/\/www.lesmissives.fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/www.lesmissives.fr\/#\/schema\/logo\/image\/","url":"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/09\/cropped-LOGO-MISSIVES-ROUGE-COMPLET2-scaled-1.jpg","contentUrl":"http:\/\/www.lesmissives.fr\/wp-content\/uploads\/2025\/09\/cropped-LOGO-MISSIVES-ROUGE-COMPLET2-scaled-1.jpg","width":1130,"height":800,"caption":"les missives"},"image":{"@id":"http:\/\/www.lesmissives.fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LesMissives\/"]},{"@type":"Person","@id":"http:\/\/www.lesmissives.fr\/#\/schema\/person\/be2f3aafb05798c1d3eae466b12b9a48","name":"Cl\u00e9mence Bauer","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/www.lesmissives.fr\/#\/schema\/person\/image\/","url":"http:\/\/1.gravatar.com\/avatar\/7383069acf91606bc26ab561adaa295a?s=96&d=mm&r=g","contentUrl":"http:\/\/1.gravatar.com\/avatar\/7383069acf91606bc26ab561adaa295a?s=96&d=mm&r=g","caption":"Cl\u00e9mence Bauer"},"description":"Entour\u00e9e de s\u0153urs, tantes, ni\u00e8ces, au c\u0153ur d'un gyn\u00e9c\u00e9e familial, observant la nature depuis toujours et \u0153uvrant dans le domaine agricole depuis 15 ans, Cl\u00e9mence a eu maintes fois l'occasion de se dire que la figure f\u00e9minine, animale ou humaine \u00e9tait plus souvent exploit\u00e9e que dirigeante. Malgr\u00e9 tout, en noyant son bonheur dans le th\u00e9 et le vin de noix, elle s'accroche au fait qu'\u00e0 chaque instant, dans chaque situation, l'\u00e9veil des consciences reste possible, et exp\u00e9rimente chaque jour qu'il n'y a de plus belle valeur que la sororit\u00e9.","url":"http:\/\/www.lesmissives.fr\/index.php\/author\/clemencebauer\/"}]}},"_links":{"self":[{"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/posts\/5212"}],"collection":[{"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/comments?post=5212"}],"version-history":[{"count":3,"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/posts\/5212\/revisions"}],"predecessor-version":[{"id":5218,"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/posts\/5212\/revisions\/5218"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/media\/5213"}],"wp:attachment":[{"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/media?parent=5212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/categories?post=5212"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.lesmissives.fr\/index.php\/wp-json\/wp\/v2\/tags?post=5212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}